{"id":235575,"date":"2023-01-11T18:32:00","date_gmt":"2023-01-11T17:32:00","guid":{"rendered":"https:\/\/www.barbie-secondlife.com\/?p=235575"},"modified":"2023-01-30T21:45:18","modified_gmt":"2023-01-30T20:45:18","slug":"galerie-barbie-idylle","status":"publish","type":"post","link":"https:\/\/www.barbie-secondlife.com\/br\/galerie-photos\/europe-est\/galerie-barbie-idylle\/","title":{"rendered":"Galeria &#8211; <a href=\"https:\/\/www.barbie-secondlife.com\/br\/barbie\/world\/europe-est\/barbie-idylle\/\">Barbie Idylle<\/a>"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\"><em><strong>Barbie Career of the Year &#8211; Judge<\/strong><\/em><\/h2>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"614\" data-src=\"https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2021\/01\/Idylle_postcard_Galerie-1024x614.jpg\" alt=\"Barbie Idylle\" class=\"wp-image-222511 lazyload\" data-srcset=\"https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2021\/01\/Idylle_postcard_Galerie-1024x614.jpg 1024w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2021\/01\/Idylle_postcard_Galerie-302x181.jpg 302w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2021\/01\/Idylle_postcard_Galerie-200x120.jpg 200w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2021\/01\/Idylle_postcard_Galerie-500x300.jpg 500w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2021\/01\/Idylle_postcard_Galerie-350x210.jpg 350w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2021\/01\/Idylle_postcard_Galerie-768x461.jpg 768w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2021\/01\/Idylle_postcard_Galerie.jpg 1080w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/614;\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"700\" height=\"600\" data-id=\"219509\" data-src=\"https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2021\/01\/Barbie_Idylle.jpg\" alt=\"Barbie Idylle\" class=\"wp-image-219509 lazyload\" data-srcset=\"https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2021\/01\/Barbie_Idylle.jpg 700w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2021\/01\/Barbie_Idylle-302x259.jpg 302w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2021\/01\/Barbie_Idylle-200x171.jpg 200w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2021\/01\/Barbie_Idylle-500x429.jpg 500w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2021\/01\/Barbie_Idylle-350x300.jpg 350w\" data-sizes=\"(max-width: 700px) 100vw, 700px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 700px; --smush-placeholder-aspect-ratio: 700\/600;\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"302\" height=\"850\" data-id=\"219511\" data-src=\"https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2021\/01\/Barbie_Idylle_Galerie_Miss.jpg\" alt=\"Barbie Idylle\" class=\"wp-image-219511 lazyload\" data-srcset=\"https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2021\/01\/Barbie_Idylle_Galerie_Miss.jpg 302w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2021\/01\/Barbie_Idylle_Galerie_Miss-200x563.jpg 200w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2021\/01\/Barbie_Idylle_Galerie_Miss-107x300.jpg 107w\" data-sizes=\"(max-width: 302px) 100vw, 302px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 302px; --smush-placeholder-aspect-ratio: 302\/850;\" \/><\/figure>\n<\/figure>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-4 is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"302\" height=\"850\" data-id=\"219515\" data-src=\"https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2021\/01\/Barbie_Idylle_Maillot_de_bain_face.jpg\" alt=\"Barbie Idylle\" class=\"wp-image-219515 lazyload\" data-srcset=\"https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2021\/01\/Barbie_Idylle_Maillot_de_bain_face.jpg 302w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2021\/01\/Barbie_Idylle_Maillot_de_bain_face-200x563.jpg 200w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2021\/01\/Barbie_Idylle_Maillot_de_bain_face-107x300.jpg 107w\" data-sizes=\"(max-width: 302px) 100vw, 302px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 302px; --smush-placeholder-aspect-ratio: 302\/850;\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"302\" height=\"850\" data-id=\"219516\" data-src=\"https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2021\/01\/Barbie_Idylle_Noir_et_Blanc.jpg\" alt=\"Barbie Idylle\" class=\"wp-image-219516 lazyload\" data-srcset=\"https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2021\/01\/Barbie_Idylle_Noir_et_Blanc.jpg 302w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2021\/01\/Barbie_Idylle_Noir_et_Blanc-200x563.jpg 200w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2021\/01\/Barbie_Idylle_Noir_et_Blanc-107x300.jpg 107w\" data-sizes=\"(max-width: 302px) 100vw, 302px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 302px; --smush-placeholder-aspect-ratio: 302\/850;\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"302\" height=\"850\" data-id=\"219514\" data-src=\"https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2021\/01\/Barbie_Idylle_Maillot_de_bain_dos.jpg\" alt=\"Barbie Idylle\" class=\"wp-image-219514 lazyload\" data-srcset=\"https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2021\/01\/Barbie_Idylle_Maillot_de_bain_dos.jpg 302w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2021\/01\/Barbie_Idylle_Maillot_de_bain_dos-200x563.jpg 200w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2021\/01\/Barbie_Idylle_Maillot_de_bain_dos-107x300.jpg 107w\" data-sizes=\"(max-width: 302px) 100vw, 302px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 302px; --smush-placeholder-aspect-ratio: 302\/850;\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"302\" height=\"850\" data-id=\"235556\" data-src=\"https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2021\/01\/Idylle.jpg\" alt=\"Barbie Idylle\" class=\"wp-image-235556 lazyload\" data-srcset=\"https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2021\/01\/Idylle.jpg 302w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2021\/01\/Idylle-200x563.jpg 200w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2021\/01\/Idylle-107x300.jpg 107w\" data-sizes=\"(max-width: 302px) 100vw, 302px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 302px; --smush-placeholder-aspect-ratio: 302\/850;\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Barbie Career of the Year &#8211; Judge<\/p>\n","protected":false},"author":1,"featured_media":219510,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[83],"tags":[1473,1972,2303,1393],"class_list":["post-235575","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-europe-est","tag-barbie-2019","tag-barbie-careers","tag-barbie-judge","tag-barbie-ooak"],"translation":{"provider":"WPGlobus","version":"3.0.2","language":"br","enabled_languages":["fr","en","es","br","de"],"languages":{"fr":{"title":true,"content":true,"excerpt":false},"en":{"title":true,"content":false,"excerpt":false},"es":{"title":true,"content":false,"excerpt":false},"br":{"title":true,"content":false,"excerpt":false},"de":{"title":true,"content":false,"excerpt":false}}},"_links":{"self":[{"href":"https:\/\/www.barbie-secondlife.com\/br\/wp-json\/wp\/v2\/posts\/235575","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.barbie-secondlife.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.barbie-secondlife.com\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.barbie-secondlife.com\/br\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.barbie-secondlife.com\/br\/wp-json\/wp\/v2\/comments?post=235575"}],"version-history":[{"count":1,"href":"https:\/\/www.barbie-secondlife.com\/br\/wp-json\/wp\/v2\/posts\/235575\/revisions"}],"predecessor-version":[{"id":596860,"href":"https:\/\/www.barbie-secondlife.com\/br\/wp-json\/wp\/v2\/posts\/235575\/revisions\/596860"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.barbie-secondlife.com\/br\/wp-json\/wp\/v2\/media\/219510"}],"wp:attachment":[{"href":"https:\/\/www.barbie-secondlife.com\/br\/wp-json\/wp\/v2\/media?parent=235575"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.barbie-secondlife.com\/br\/wp-json\/wp\/v2\/categories?post=235575"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.barbie-secondlife.com\/br\/wp-json\/wp\/v2\/tags?post=235575"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}