{"id":9905,"date":"2023-09-01T15:24:00","date_gmt":"2023-09-01T13:24:00","guid":{"rendered":"http:\/\/www.barbie-secondlife.com\/?p=9905"},"modified":"2024-01-28T22:42:29","modified_gmt":"2024-01-28T21:42:29","slug":"galerie-barbie-grazziella","status":"publish","type":"post","link":"https:\/\/www.barbie-secondlife.com\/de\/galerie-photos\/europe-ouest\/galerie-barbie-grazziella\/","title":{"rendered":"Fotogalerie \u2013 <a href=\"https:\/\/www.barbie-secondlife.com\/de\/barbie\/world\/europe-ouest\/barbie-grazziella\/\">Barbie Grazziella<\/a>"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\"><em><strong>Barbie Collection Birthday Wishes 2017<\/strong><\/em><\/h2>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"614\" data-id=\"21281\" data-src=\"https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2020\/04\/grazziella-1024x614.jpg\" alt=\"Barbie Grazziella\" class=\"wp-image-21281 lazyload\" data-srcset=\"https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2020\/04\/grazziella-1024x614.jpg 1024w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2020\/04\/grazziella-302x181.jpg 302w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2020\/04\/grazziella-200x120.jpg 200w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2020\/04\/grazziella-500x300.jpg 500w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2020\/04\/grazziella-350x210.jpg 350w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2020\/04\/grazziella-768x461.jpg 768w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2020\/04\/grazziella.jpg 1080w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/614;\" \/><\/figure>\n<\/figure>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-1 wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2018\/10\/Grazziella.jpg\"><img decoding=\"async\" width=\"625\" height=\"500\" data-id=\"14206\" data-src=\"https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2018\/10\/Grazziella.jpg\" alt=\"Miss Barbie Grazziella\" class=\"wp-image-14206 lazyload\" data-srcset=\"https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2018\/10\/Grazziella.jpg 625w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2018\/10\/Grazziella-302x242.jpg 302w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2018\/10\/Grazziella-200x160.jpg 200w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2018\/10\/Grazziella-500x400.jpg 500w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2018\/10\/Grazziella-350x280.jpg 350w\" data-sizes=\"(max-width: 625px) 100vw, 625px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 625px; --smush-placeholder-aspect-ratio: 625\/500;\" \/><\/a><\/figure>\n<\/figure>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-2 is-cropped wp-block-gallery-3 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2017\/10\/Barbie_Grazziella.jpg\"><img decoding=\"async\" width=\"700\" height=\"600\" data-id=\"10020\" data-src=\"https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2017\/10\/Barbie_Grazziella.jpg\" alt=\"Barbie Grazziella\" class=\"wp-image-10020 lazyload\" data-srcset=\"https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2017\/10\/Barbie_Grazziella.jpg 700w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2017\/10\/Barbie_Grazziella-302x259.jpg 302w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2017\/10\/Barbie_Grazziella-200x171.jpg 200w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2017\/10\/Barbie_Grazziella-500x429.jpg 500w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2017\/10\/Barbie_Grazziella-350x300.jpg 350w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2017\/10\/Barbie_Grazziella-300x257.jpg 300w\" data-sizes=\"(max-width: 700px) 100vw, 700px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 700px; --smush-placeholder-aspect-ratio: 700\/600;\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2017\/10\/Barbie-Grazziella-Galerie-Miss.jpg\"><img decoding=\"async\" width=\"283\" height=\"425\" data-id=\"10022\" data-src=\"https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2017\/10\/Barbie-Grazziella-Galerie-Miss.jpg\" alt=\"Barbie Grazziella\" class=\"wp-image-10022 lazyload\" data-srcset=\"https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2017\/10\/Barbie-Grazziella-Galerie-Miss.jpg 283w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2017\/10\/Barbie-Grazziella-Galerie-Miss-200x300.jpg 200w\" data-sizes=\"(max-width: 283px) 100vw, 283px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 283px; --smush-placeholder-aspect-ratio: 283\/425;\" \/><\/a><\/figure>\n<\/figure>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-4 is-cropped wp-block-gallery-4 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2017\/10\/Barbie_Grazziella_Maillot_de_Bain_face.jpg\"><img decoding=\"async\" width=\"302\" height=\"850\" data-id=\"10018\" data-src=\"https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2017\/10\/Barbie_Grazziella_Maillot_de_Bain_face.jpg\" alt=\"Barbie Grazziella\" class=\"wp-image-10018 lazyload\" data-srcset=\"https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2017\/10\/Barbie_Grazziella_Maillot_de_Bain_face.jpg 302w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2017\/10\/Barbie_Grazziella_Maillot_de_Bain_face-200x563.jpg 200w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2017\/10\/Barbie_Grazziella_Maillot_de_Bain_face-107x300.jpg 107w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2017\/10\/Barbie_Grazziella_Maillot_de_Bain_face-151x425.jpg 151w\" data-sizes=\"(max-width: 302px) 100vw, 302px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 302px; --smush-placeholder-aspect-ratio: 302\/850;\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2017\/10\/Barbie_Grazziella_Noir_et_Blanc.jpg\"><img decoding=\"async\" width=\"302\" height=\"850\" data-id=\"10019\" data-src=\"https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2017\/10\/Barbie_Grazziella_Noir_et_Blanc.jpg\" alt=\"Barbie Grazziella\" class=\"wp-image-10019 lazyload\" data-srcset=\"https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2017\/10\/Barbie_Grazziella_Noir_et_Blanc.jpg 302w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2017\/10\/Barbie_Grazziella_Noir_et_Blanc-200x563.jpg 200w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2017\/10\/Barbie_Grazziella_Noir_et_Blanc-107x300.jpg 107w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2017\/10\/Barbie_Grazziella_Noir_et_Blanc-151x425.jpg 151w\" data-sizes=\"(max-width: 302px) 100vw, 302px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 302px; --smush-placeholder-aspect-ratio: 302\/850;\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2017\/10\/Barbie_Grazziella_Maillot_de_Bain_dos.jpg\"><img decoding=\"async\" width=\"302\" height=\"850\" data-id=\"10017\" data-src=\"https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2017\/10\/Barbie_Grazziella_Maillot_de_Bain_dos.jpg\" alt=\"Barbie Grazziella\" class=\"wp-image-10017 lazyload\" data-srcset=\"https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2017\/10\/Barbie_Grazziella_Maillot_de_Bain_dos.jpg 302w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2017\/10\/Barbie_Grazziella_Maillot_de_Bain_dos-200x563.jpg 200w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2017\/10\/Barbie_Grazziella_Maillot_de_Bain_dos-107x300.jpg 107w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2017\/10\/Barbie_Grazziella_Maillot_de_Bain_dos-151x425.jpg 151w\" data-sizes=\"(max-width: 302px) 100vw, 302px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 302px; --smush-placeholder-aspect-ratio: 302\/850;\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2017\/10\/Grazziella.jpg\"><img decoding=\"async\" width=\"302\" height=\"850\" data-id=\"17406\" data-src=\"https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2017\/10\/Grazziella.jpg\" alt=\"Barbie Grazziella\" class=\"wp-image-17406 lazyload\" data-srcset=\"https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2017\/10\/Grazziella.jpg 302w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2017\/10\/Grazziella-200x563.jpg 200w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2017\/10\/Grazziella-107x300.jpg 107w\" data-sizes=\"(max-width: 302px) 100vw, 302px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 302px; --smush-placeholder-aspect-ratio: 302\/850;\" \/><\/a><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Barbie Collection Birthday Wishes 2017<\/p>\n","protected":false},"author":1,"featured_media":10021,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"gallery","meta":{"footnotes":""},"categories":[82],"tags":[1497,1488,1933,1483,1465],"class_list":["post-9905","post","type-post","status-publish","format-gallery","has-post-thumbnail","hentry","category-europe-ouest","tag-barbie-2017","tag-barbie-birthday-wishes","tag-barbie-birthday-wishes-2017","tag-barbie-carlyle-nuera","tag-barbie-pink-label","post_format-post-format-gallery"],"translation":{"provider":"WPGlobus","version":"3.0.2","language":"de","enabled_languages":["fr","en","es","br","de"],"languages":{"fr":{"title":true,"content":true,"excerpt":false},"en":{"title":true,"content":false,"excerpt":false},"es":{"title":true,"content":false,"excerpt":false},"br":{"title":true,"content":false,"excerpt":false},"de":{"title":true,"content":false,"excerpt":false}}},"_links":{"self":[{"href":"https:\/\/www.barbie-secondlife.com\/de\/wp-json\/wp\/v2\/posts\/9905","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.barbie-secondlife.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.barbie-secondlife.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.barbie-secondlife.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.barbie-secondlife.com\/de\/wp-json\/wp\/v2\/comments?post=9905"}],"version-history":[{"count":1,"href":"https:\/\/www.barbie-secondlife.com\/de\/wp-json\/wp\/v2\/posts\/9905\/revisions"}],"predecessor-version":[{"id":596271,"href":"https:\/\/www.barbie-secondlife.com\/de\/wp-json\/wp\/v2\/posts\/9905\/revisions\/596271"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.barbie-secondlife.com\/de\/wp-json\/wp\/v2\/media\/10021"}],"wp:attachment":[{"href":"https:\/\/www.barbie-secondlife.com\/de\/wp-json\/wp\/v2\/media?parent=9905"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.barbie-secondlife.com\/de\/wp-json\/wp\/v2\/categories?post=9905"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.barbie-secondlife.com\/de\/wp-json\/wp\/v2\/tags?post=9905"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}