{"id":605089,"date":"2025-07-27T20:52:48","date_gmt":"2025-07-27T18:52:48","guid":{"rendered":"https:\/\/www.barbie-secondlife.com\/?page_id=605089"},"modified":"2025-09-30T00:09:46","modified_gmt":"2025-09-29T22:09:46","slug":"barbie-nexts-top-model-amerique-du-sud","status":"publish","type":"page","link":"https:\/\/www.barbie-secondlife.com\/en\/evenements\/barbies-next-top-model-2025\/barbie-nexts-top-model-amerique-du-sud\/","title":{"rendered":"Barbie&#8217;s Next Top Model &#8211; South America"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"700\" height=\"184\" data-src=\"https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2025\/07\/BNTM-1.gif\" alt=\"Barbie Next's Top Model\" class=\"wp-image-604981 lazyload\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 700px; --smush-placeholder-aspect-ratio: 700\/184;\" \/><\/figure>\n<\/div>\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile is-vertically-aligned-center\"><figure class=\"wp-block-media-text__media\"><img decoding=\"async\" width=\"500\" height=\"500\" data-src=\"https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2025\/09\/GAGNANTE_AMERIQUESUD.png\" alt=\"Barbie's Next Top Model 2025\" class=\"wp-image-606970 size-full lazyload\" data-srcset=\"https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2025\/09\/GAGNANTE_AMERIQUESUD.png 500w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2025\/09\/GAGNANTE_AMERIQUESUD-350x350.png 350w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2025\/09\/GAGNANTE_AMERIQUESUD-300x300.png 300w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2025\/09\/GAGNANTE_AMERIQUESUD-302x302.png 302w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2025\/09\/GAGNANTE_AMERIQUESUD-200x200.png 200w\" data-sizes=\"(max-width: 500px) 100vw, 500px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 500px; --smush-placeholder-aspect-ratio: 500\/500;\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p><strong><span style=\"text-decoration: underline;\">South America<\/span><\/strong> : A three-piece outfit composed of a <strong>bandeau-style tied top<\/strong>, wide <strong>high-waisted pants<\/strong>, and a matching <strong>long flowing coat<\/strong>. The coat, worn open, adds a regal presence to the silhouette, while the bandeau subtly reveals the shoulders, striking a perfect balance between modernity and cultural heritage. <strong>Large dangling earrings<\/strong>, adorned with pearls and golden accents, add a final touch of sophistication, affirming a look that is both bold, powerful, and deeply stylish.<br>A festive and exuberant outfit that celebrates <strong>Latin American passion and traditions.<\/strong><\/p>\n<\/div><\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"has-text-align-center has-text-color has-link-color wp-elements-99471e33ed98010354453983224e570d\" style=\"color:#b61b66;font-size:24px\"><strong>RESULTS<\/strong><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<figure class=\"wp-block-table aligncenter\"><table class=\"has-fixed-layout\"><tbody><tr><td class=\"has-text-align-center\" data-align=\"center\"><img decoding=\"async\" width=\"400\" height=\"800\" class=\"wp-image-606051 lazyload\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/800;text-align: start; white-space: normal;\" data-src=\"https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2025\/08\/BarbiesNextTopModel_Catriona_AmeriqueSud.jpg\" alt=\"Barbie's Next Top Model 2025\" data-srcset=\"https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2025\/08\/BarbiesNextTopModel_Catriona_AmeriqueSud.jpg 400w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2025\/08\/BarbiesNextTopModel_Catriona_AmeriqueSud-302x604.jpg 302w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2025\/08\/BarbiesNextTopModel_Catriona_AmeriqueSud-200x400.jpg 200w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2025\/08\/BarbiesNextTopModel_Catriona_AmeriqueSud-350x700.jpg 350w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2025\/08\/BarbiesNextTopModel_Catriona_AmeriqueSud-150x300.jpg 150w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td class=\"has-text-align-center\" data-align=\"center\"><img decoding=\"async\" width=\"400\" height=\"800\" class=\"wp-image-606059 lazyload\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/800;width: px;\" data-src=\"https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2025\/08\/BarbiesNextTopModel_Iqra_AmeriqueSud.jpg\" alt=\"Barbie's Next Top Model 2025\" data-srcset=\"https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2025\/08\/BarbiesNextTopModel_Iqra_AmeriqueSud.jpg 400w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2025\/08\/BarbiesNextTopModel_Iqra_AmeriqueSud-302x604.jpg 302w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2025\/08\/BarbiesNextTopModel_Iqra_AmeriqueSud-200x400.jpg 200w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2025\/08\/BarbiesNextTopModel_Iqra_AmeriqueSud-350x700.jpg 350w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2025\/08\/BarbiesNextTopModel_Iqra_AmeriqueSud-150x300.jpg 150w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td class=\"has-text-align-center\" data-align=\"center\"><img decoding=\"async\" width=\"400\" height=\"800\" class=\"wp-image-606061 lazyload\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/800;text-align: start; white-space: normal;\" data-src=\"https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2025\/08\/BarbiesNextTopModel_Marysia_AmeriqueSud.jpg\" alt=\"Barbie's Next Top Model 2025\" data-srcset=\"https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2025\/08\/BarbiesNextTopModel_Marysia_AmeriqueSud.jpg 400w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2025\/08\/BarbiesNextTopModel_Marysia_AmeriqueSud-302x604.jpg 302w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2025\/08\/BarbiesNextTopModel_Marysia_AmeriqueSud-200x400.jpg 200w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2025\/08\/BarbiesNextTopModel_Marysia_AmeriqueSud-350x700.jpg 350w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2025\/08\/BarbiesNextTopModel_Marysia_AmeriqueSud-150x300.jpg 150w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>VOTE : 15<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\"><strong>VOTE : 11<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\"><strong>VOTE : 10<\/strong><\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<figure class=\"wp-block-table aligncenter\"><table class=\"has-fixed-layout\"><tbody><tr><td class=\"has-text-align-center\" data-align=\"center\"><img decoding=\"async\" width=\"400\" height=\"800\" class=\"wp-image-606065 lazyload\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/800;text-align: start; white-space: normal;\" data-src=\"https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2025\/08\/BarbiesNextTopModel_Vesna_AmeriqueSud.jpg\" alt=\"Barbie's Next Top Model 2025\" data-srcset=\"https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2025\/08\/BarbiesNextTopModel_Vesna_AmeriqueSud.jpg 400w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2025\/08\/BarbiesNextTopModel_Vesna_AmeriqueSud-302x604.jpg 302w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2025\/08\/BarbiesNextTopModel_Vesna_AmeriqueSud-200x400.jpg 200w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2025\/08\/BarbiesNextTopModel_Vesna_AmeriqueSud-350x700.jpg 350w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2025\/08\/BarbiesNextTopModel_Vesna_AmeriqueSud-150x300.jpg 150w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td class=\"has-text-align-center\" data-align=\"center\"><img decoding=\"async\" width=\"400\" height=\"800\" class=\"wp-image-606050 lazyload\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/800;text-align: start; white-space: normal;\" data-src=\"https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2025\/08\/BarbiesNextTopModel_Beryl_AmeriqueSud.jpg\" alt=\"Barbie's Next Top Model 2025\" data-srcset=\"https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2025\/08\/BarbiesNextTopModel_Beryl_AmeriqueSud.jpg 400w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2025\/08\/BarbiesNextTopModel_Beryl_AmeriqueSud-302x604.jpg 302w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2025\/08\/BarbiesNextTopModel_Beryl_AmeriqueSud-200x400.jpg 200w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2025\/08\/BarbiesNextTopModel_Beryl_AmeriqueSud-350x700.jpg 350w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2025\/08\/BarbiesNextTopModel_Beryl_AmeriqueSud-150x300.jpg 150w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td class=\"has-text-align-center\" data-align=\"center\"><img decoding=\"async\" width=\"400\" height=\"800\" class=\"wp-image-606064 lazyload\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/800;text-align: start; white-space: normal;\" data-src=\"https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2025\/08\/BarbiesNextTopModel_Rita_AmeriqueSud.jpg\" alt=\"Barbie's Next Top Model 2025\" data-srcset=\"https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2025\/08\/BarbiesNextTopModel_Rita_AmeriqueSud.jpg 400w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2025\/08\/BarbiesNextTopModel_Rita_AmeriqueSud-302x604.jpg 302w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2025\/08\/BarbiesNextTopModel_Rita_AmeriqueSud-200x400.jpg 200w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2025\/08\/BarbiesNextTopModel_Rita_AmeriqueSud-350x700.jpg 350w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2025\/08\/BarbiesNextTopModel_Rita_AmeriqueSud-150x300.jpg 150w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>VOTE : 9<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\"><strong>VOTE : 7<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\"><strong>VOTE : 7<\/strong><\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<figure class=\"wp-block-table aligncenter\"><table class=\"has-fixed-layout\"><tbody><tr><td class=\"has-text-align-center\" data-align=\"center\"><img decoding=\"async\" width=\"400\" height=\"800\" class=\"wp-image-606060 lazyload\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/800;width: px;\" data-src=\"https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2025\/08\/BarbiesNextTopModel_Majka_AmeriqueSud.jpg\" alt=\"Barbie's Next Top Model 2025\" data-srcset=\"https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2025\/08\/BarbiesNextTopModel_Majka_AmeriqueSud.jpg 400w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2025\/08\/BarbiesNextTopModel_Majka_AmeriqueSud-302x604.jpg 302w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2025\/08\/BarbiesNextTopModel_Majka_AmeriqueSud-200x400.jpg 200w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2025\/08\/BarbiesNextTopModel_Majka_AmeriqueSud-350x700.jpg 350w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2025\/08\/BarbiesNextTopModel_Majka_AmeriqueSud-150x300.jpg 150w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td class=\"has-text-align-center\" data-align=\"center\"><img decoding=\"async\" width=\"400\" height=\"800\" class=\"wp-image-606054 lazyload\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/800;text-align: start; white-space: normal;\" data-src=\"https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2025\/08\/BarbiesNextTopModel_Eleanor_AmeriqueSud.jpg\" alt=\"Barbie's Next Top Model 2025\" data-srcset=\"https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2025\/08\/BarbiesNextTopModel_Eleanor_AmeriqueSud.jpg 400w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2025\/08\/BarbiesNextTopModel_Eleanor_AmeriqueSud-302x604.jpg 302w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2025\/08\/BarbiesNextTopModel_Eleanor_AmeriqueSud-200x400.jpg 200w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2025\/08\/BarbiesNextTopModel_Eleanor_AmeriqueSud-350x700.jpg 350w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2025\/08\/BarbiesNextTopModel_Eleanor_AmeriqueSud-150x300.jpg 150w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td class=\"has-text-align-center\" data-align=\"center\"><img decoding=\"async\" width=\"400\" height=\"800\" class=\"wp-image-606058 lazyload\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/800;width: px;\" data-src=\"https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2025\/08\/BarbiesNextTopModel_Hadeel_AmeriqueSud.jpg\" alt=\"Barbie's Next Top Model 2025\" data-srcset=\"https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2025\/08\/BarbiesNextTopModel_Hadeel_AmeriqueSud.jpg 400w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2025\/08\/BarbiesNextTopModel_Hadeel_AmeriqueSud-302x604.jpg 302w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2025\/08\/BarbiesNextTopModel_Hadeel_AmeriqueSud-200x400.jpg 200w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2025\/08\/BarbiesNextTopModel_Hadeel_AmeriqueSud-350x700.jpg 350w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2025\/08\/BarbiesNextTopModel_Hadeel_AmeriqueSud-150x300.jpg 150w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>VOTE : 6<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\"><strong>VOTE : 5<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\"><strong>VOTE : 5<\/strong><\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<figure class=\"wp-block-table aligncenter\"><table class=\"has-fixed-layout\"><tbody><tr><td class=\"has-text-align-center\" data-align=\"center\"><img decoding=\"async\" width=\"400\" height=\"800\" class=\"wp-image-606052 lazyload\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/800;text-align: start; white-space: normal;\" data-src=\"https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2025\/08\/BarbiesNextTopModel_Chantou_AmeriqueSud.jpg\" alt=\"Barbie's Next Top Model 2025\" data-srcset=\"https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2025\/08\/BarbiesNextTopModel_Chantou_AmeriqueSud.jpg 400w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2025\/08\/BarbiesNextTopModel_Chantou_AmeriqueSud-302x604.jpg 302w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2025\/08\/BarbiesNextTopModel_Chantou_AmeriqueSud-200x400.jpg 200w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2025\/08\/BarbiesNextTopModel_Chantou_AmeriqueSud-350x700.jpg 350w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2025\/08\/BarbiesNextTopModel_Chantou_AmeriqueSud-150x300.jpg 150w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td class=\"has-text-align-center\" data-align=\"center\"><img decoding=\"async\" width=\"400\" height=\"800\" class=\"wp-image-606053 lazyload\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/800;text-align: start; white-space: normal;\" data-src=\"https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2025\/08\/BarbiesNextTopModel_Deborah_AmeriqueSud.jpg\" alt=\"Barbie's Next Top Model 2025\" data-srcset=\"https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2025\/08\/BarbiesNextTopModel_Deborah_AmeriqueSud.jpg 400w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2025\/08\/BarbiesNextTopModel_Deborah_AmeriqueSud-302x604.jpg 302w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2025\/08\/BarbiesNextTopModel_Deborah_AmeriqueSud-200x400.jpg 200w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2025\/08\/BarbiesNextTopModel_Deborah_AmeriqueSud-350x700.jpg 350w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2025\/08\/BarbiesNextTopModel_Deborah_AmeriqueSud-150x300.jpg 150w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td class=\"has-text-align-center\" data-align=\"center\"><img decoding=\"async\" width=\"400\" height=\"800\" class=\"wp-image-606055 lazyload\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/800;text-align: start; white-space: normal;\" data-src=\"https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2025\/08\/BarbiesNextTopModel_Franka_AmeriqueSud.jpg\" alt=\"Barbie's Next Top Model 2025\" data-srcset=\"https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2025\/08\/BarbiesNextTopModel_Franka_AmeriqueSud.jpg 400w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2025\/08\/BarbiesNextTopModel_Franka_AmeriqueSud-302x604.jpg 302w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2025\/08\/BarbiesNextTopModel_Franka_AmeriqueSud-200x400.jpg 200w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2025\/08\/BarbiesNextTopModel_Franka_AmeriqueSud-350x700.jpg 350w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2025\/08\/BarbiesNextTopModel_Franka_AmeriqueSud-150x300.jpg 150w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>VOTE : 4<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\"><strong>VOTE : 3<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\"><strong>VOTE : 3<\/strong><\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<figure class=\"wp-block-table aligncenter\"><table class=\"has-fixed-layout\"><tbody><tr><td class=\"has-text-align-center\" data-align=\"center\"><img decoding=\"async\" width=\"400\" height=\"800\" class=\"wp-image-606063 lazyload\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/800;width: px;\" data-src=\"https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2025\/08\/BarbiesNextTopModel_Nichelle_AmeriqueSud.jpg\" alt=\"Barbie's Next Top Model 2025\" data-srcset=\"https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2025\/08\/BarbiesNextTopModel_Nichelle_AmeriqueSud.jpg 400w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2025\/08\/BarbiesNextTopModel_Nichelle_AmeriqueSud-302x604.jpg 302w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2025\/08\/BarbiesNextTopModel_Nichelle_AmeriqueSud-200x400.jpg 200w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2025\/08\/BarbiesNextTopModel_Nichelle_AmeriqueSud-350x700.jpg 350w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2025\/08\/BarbiesNextTopModel_Nichelle_AmeriqueSud-150x300.jpg 150w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td class=\"has-text-align-center\" data-align=\"center\"><img decoding=\"async\" width=\"400\" height=\"800\" class=\"wp-image-606056 lazyload\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/800;text-align: start; white-space: normal;\" data-src=\"https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2025\/08\/BarbiesNextTopModel_Griselda_AmeriqueSud.jpg\" alt=\"Barbie's Next Top Model 2025\" data-srcset=\"https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2025\/08\/BarbiesNextTopModel_Griselda_AmeriqueSud.jpg 400w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2025\/08\/BarbiesNextTopModel_Griselda_AmeriqueSud-302x604.jpg 302w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2025\/08\/BarbiesNextTopModel_Griselda_AmeriqueSud-200x400.jpg 200w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2025\/08\/BarbiesNextTopModel_Griselda_AmeriqueSud-350x700.jpg 350w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2025\/08\/BarbiesNextTopModel_Griselda_AmeriqueSud-150x300.jpg 150w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><td class=\"has-text-align-center\" data-align=\"center\"><img decoding=\"async\" width=\"400\" height=\"800\" class=\"wp-image-606062 lazyload\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/800;text-align: start; white-space: normal;\" data-src=\"https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2025\/08\/BarbiesNextTopModel_Maya_AmeriqueSud.jpg\" alt=\"Barbie's Next Top Model 2025\" data-srcset=\"https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2025\/08\/BarbiesNextTopModel_Maya_AmeriqueSud.jpg 400w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2025\/08\/BarbiesNextTopModel_Maya_AmeriqueSud-302x604.jpg 302w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2025\/08\/BarbiesNextTopModel_Maya_AmeriqueSud-200x400.jpg 200w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2025\/08\/BarbiesNextTopModel_Maya_AmeriqueSud-350x700.jpg 350w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2025\/08\/BarbiesNextTopModel_Maya_AmeriqueSud-150x300.jpg 150w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>VOTE : 3<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\"><strong>VOTE : 3<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\"><strong>VOTE : 2<\/strong><\/td><\/tr><\/tbody><\/table><\/figure>\n<\/div>\n<\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>South America : A three-piece outfit composed of a bandeau-style tied top, wide high-waisted pants, and a matching long flowing coat. The coat, worn open, adds a regal presence to the silhouette, while the bandeau subtly reveals the shoulders, striking a perfect balance between modernity and cultural heritage. Large dangling earrings, adorned with pearls and [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":604768,"parent":604767,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-605089","page","type-page","status-publish","has-post-thumbnail","hentry"],"translation":{"provider":"WPGlobus","version":"3.0.2","language":"en","enabled_languages":["fr","en","es","br","de"],"languages":{"fr":{"title":true,"content":true,"excerpt":false},"en":{"title":true,"content":true,"excerpt":false},"es":{"title":true,"content":true,"excerpt":false},"br":{"title":true,"content":true,"excerpt":false},"de":{"title":true,"content":true,"excerpt":false}}},"_links":{"self":[{"href":"https:\/\/www.barbie-secondlife.com\/en\/wp-json\/wp\/v2\/pages\/605089","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.barbie-secondlife.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.barbie-secondlife.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.barbie-secondlife.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.barbie-secondlife.com\/en\/wp-json\/wp\/v2\/comments?post=605089"}],"version-history":[{"count":20,"href":"https:\/\/www.barbie-secondlife.com\/en\/wp-json\/wp\/v2\/pages\/605089\/revisions"}],"predecessor-version":[{"id":606975,"href":"https:\/\/www.barbie-secondlife.com\/en\/wp-json\/wp\/v2\/pages\/605089\/revisions\/606975"}],"up":[{"embeddable":true,"href":"https:\/\/www.barbie-secondlife.com\/en\/wp-json\/wp\/v2\/pages\/604767"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.barbie-secondlife.com\/en\/wp-json\/wp\/v2\/media\/604768"}],"wp:attachment":[{"href":"https:\/\/www.barbie-secondlife.com\/en\/wp-json\/wp\/v2\/media?parent=605089"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}