{"id":16843,"date":"2023-01-06T17:39:00","date_gmt":"2023-01-06T16:39:00","guid":{"rendered":"http:\/\/www.barbie-secondlife.com\/?p=16843"},"modified":"2023-01-30T21:44:42","modified_gmt":"2023-01-30T20:44:42","slug":"galerie-barbie-romina","status":"publish","type":"post","link":"https:\/\/www.barbie-secondlife.com\/es\/galerie-photos\/amerique-sud\/galerie-barbie-romina\/","title":{"rendered":"Galer\u00eda &#8211; <a href=\"https:\/\/www.barbie-secondlife.com\/es\/barbie\/world\/amerique-du-sud\/barbie-romina\/\">Barbie Romina<\/a>"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\"><em><strong>Barbie Harley-Davidson And Ken Giftset<\/strong><\/em><\/h2>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"614\" data-id=\"21065\" data-src=\"https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2020\/04\/romina-1024x614.jpg\" alt=\"Barbie Romina\" class=\"wp-image-21065 lazyload\" data-srcset=\"https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2020\/04\/romina-1024x614.jpg 1024w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2020\/04\/romina-302x181.jpg 302w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2020\/04\/romina-200x120.jpg 200w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2020\/04\/romina-500x300.jpg 500w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2020\/04\/romina-350x210.jpg 350w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2020\/04\/romina-768x461.jpg 768w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2020\/04\/romina.jpg 1080w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/614;\" \/><\/figure>\n<\/figure>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"700\" height=\"600\" data-id=\"16390\" data-src=\"https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2019\/02\/Barbie_Romina.jpg\" alt=\"Barbie Romina\" class=\"wp-image-16390 lazyload\" data-srcset=\"https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2019\/02\/Barbie_Romina.jpg 700w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2019\/02\/Barbie_Romina-302x259.jpg 302w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2019\/02\/Barbie_Romina-200x171.jpg 200w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2019\/02\/Barbie_Romina-500x429.jpg 500w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2019\/02\/Barbie_Romina-350x300.jpg 350w\" data-sizes=\"(max-width: 700px) 100vw, 700px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 700px; --smush-placeholder-aspect-ratio: 700\/600;\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"567\" height=\"850\" data-id=\"16649\" data-src=\"https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2019\/03\/Barbie_Romina_Galerie_Miss.jpg\" alt=\"\" class=\"wp-image-16649 lazyload\" data-srcset=\"https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2019\/03\/Barbie_Romina_Galerie_Miss.jpg 567w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2019\/03\/Barbie_Romina_Galerie_Miss-302x453.jpg 302w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2019\/03\/Barbie_Romina_Galerie_Miss-200x300.jpg 200w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2019\/03\/Barbie_Romina_Galerie_Miss-500x750.jpg 500w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2019\/03\/Barbie_Romina_Galerie_Miss-350x525.jpg 350w\" data-sizes=\"(max-width: 567px) 100vw, 567px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 567px; --smush-placeholder-aspect-ratio: 567\/850;\" \/><\/figure>\n<\/figure>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-4 is-cropped wp-block-gallery-3 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"302\" height=\"850\" data-id=\"16133\" data-src=\"https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2019\/02\/Barbie_Romina_Maillot_de_bain_face.jpg\" alt=\"\" class=\"wp-image-16133 lazyload\" data-srcset=\"https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2019\/02\/Barbie_Romina_Maillot_de_bain_face.jpg 302w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2019\/02\/Barbie_Romina_Maillot_de_bain_face-200x563.jpg 200w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2019\/02\/Barbie_Romina_Maillot_de_bain_face-107x300.jpg 107w\" data-sizes=\"(max-width: 302px) 100vw, 302px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 302px; --smush-placeholder-aspect-ratio: 302\/850;\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"302\" height=\"850\" data-id=\"16267\" data-src=\"https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2019\/02\/Barbie_Romina_Noir_et_Blanc.jpg\" alt=\"\" class=\"wp-image-16267 lazyload\" data-srcset=\"https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2019\/02\/Barbie_Romina_Noir_et_Blanc.jpg 302w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2019\/02\/Barbie_Romina_Noir_et_Blanc-200x563.jpg 200w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2019\/02\/Barbie_Romina_Noir_et_Blanc-107x300.jpg 107w\" data-sizes=\"(max-width: 302px) 100vw, 302px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 302px; --smush-placeholder-aspect-ratio: 302\/850;\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"302\" height=\"850\" data-id=\"16132\" data-src=\"https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2019\/02\/Barbie_Romina_Maillot_de_bain_dos.jpg\" alt=\"\" class=\"wp-image-16132 lazyload\" data-srcset=\"https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2019\/02\/Barbie_Romina_Maillot_de_bain_dos.jpg 302w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2019\/02\/Barbie_Romina_Maillot_de_bain_dos-200x563.jpg 200w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2019\/02\/Barbie_Romina_Maillot_de_bain_dos-107x300.jpg 107w\" data-sizes=\"(max-width: 302px) 100vw, 302px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 302px; --smush-placeholder-aspect-ratio: 302\/850;\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"302\" height=\"850\" data-id=\"16206\" data-src=\"https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2019\/02\/Romina.jpg\" alt=\"\" class=\"wp-image-16206 lazyload\" data-srcset=\"https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2019\/02\/Romina.jpg 302w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2019\/02\/Romina-200x563.jpg 200w, https:\/\/www.barbie-secondlife.com\/wp-content\/uploads\/2019\/02\/Romina-107x300.jpg 107w\" data-sizes=\"(max-width: 302px) 100vw, 302px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 302px; --smush-placeholder-aspect-ratio: 302\/850;\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Barbie Harley-Davidson And Ken Giftset<\/p>\n","protected":false},"author":1,"featured_media":16451,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[84],"tags":[1415,2281,1393,1465],"class_list":["post-16843","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-amerique-sud","tag-barbie-2010","tag-barbie-harley-davidson","tag-barbie-ooak","tag-barbie-pink-label"],"translation":{"provider":"WPGlobus","version":"3.0.2","language":"es","enabled_languages":["fr","en","es","br","de"],"languages":{"fr":{"title":true,"content":true,"excerpt":false},"en":{"title":true,"content":false,"excerpt":false},"es":{"title":true,"content":false,"excerpt":false},"br":{"title":true,"content":false,"excerpt":false},"de":{"title":true,"content":false,"excerpt":false}}},"_links":{"self":[{"href":"https:\/\/www.barbie-secondlife.com\/es\/wp-json\/wp\/v2\/posts\/16843","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.barbie-secondlife.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.barbie-secondlife.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.barbie-secondlife.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.barbie-secondlife.com\/es\/wp-json\/wp\/v2\/comments?post=16843"}],"version-history":[{"count":1,"href":"https:\/\/www.barbie-secondlife.com\/es\/wp-json\/wp\/v2\/posts\/16843\/revisions"}],"predecessor-version":[{"id":596870,"href":"https:\/\/www.barbie-secondlife.com\/es\/wp-json\/wp\/v2\/posts\/16843\/revisions\/596870"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.barbie-secondlife.com\/es\/wp-json\/wp\/v2\/media\/16451"}],"wp:attachment":[{"href":"https:\/\/www.barbie-secondlife.com\/es\/wp-json\/wp\/v2\/media?parent=16843"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.barbie-secondlife.com\/es\/wp-json\/wp\/v2\/categories?post=16843"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.barbie-secondlife.com\/es\/wp-json\/wp\/v2\/tags?post=16843"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}